{"id":3,"date":"2022-09-13T07:47:54","date_gmt":"2022-09-13T07:47:54","guid":{"rendered":"https:\/\/cad.nl\/?page_id=3"},"modified":"2025-02-12T14:03:04","modified_gmt":"2025-02-12T14:03:04","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/cad.nl\/de\/privacy-policy\/","title":{"rendered":"Datenschutzrichtlinie"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58bd361 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58bd361\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-85b9528\" data-id=\"85b9528\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-257613f elementor-icon-list--layout-inline elementor-align-start elementor-mobile-align-center elementor-list-item-link-inline elementor-widget elementor-widget-icon-list\" data-id=\"257613f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:0332580080\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+033 258 0080<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:info@tomassen.nl\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@tomassen.nl<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-map-marker-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tomassen ICT Services<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-610c138\" data-id=\"610c138\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3eaaeef elementor-icon-list--layout-inline elementor-align-end elementor-mobile-align-start elementor-hidden-mobile elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3eaaeef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/es.linkedin.com\/company\/tomassen-ict-services\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-linkedin-in\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/tomassenprinting\/?hl=en\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a1b8abf\" data-id=\"a1b8abf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90ccc01 elementor-search-form--skin-minimal elementor-hidden-mobile elementor-widget elementor-widget-search-form\" data-id=\"90ccc01\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;minimal&quot;}\" data-widget_type=\"search-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<search role=\"search\">\n\t\t\t<form class=\"elementor-search-form\" action=\"https:\/\/cad.nl\/de\" method=\"get\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-search-form__container\">\n\t\t\t\t\t<label class=\"elementor-screen-only\" for=\"elementor-search-form-90ccc01\">Suche<\/label>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-search-form__icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search\"><\/i>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Suche<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t<input id=\"elementor-search-form-90ccc01\" placeholder=\"Zoek\" class=\"elementor-search-form__input\" type=\"search\" name=\"s\" value=\"\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t<\/search>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d001a52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d001a52\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6622362\" data-id=\"6622362\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99ec505 elementor-widget elementor-widget-image\" data-id=\"99ec505\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/www.cad.nl\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"163\" src=\"https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2.png\" class=\"attachment-full size-full wp-image-6233\" alt=\"\" srcset=\"https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2.png 829w, https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2-300x59.png 300w, https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2-768x151.png 768w, https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2-600x118.png 600w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a859c0a\" data-id=\"a859c0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9445714 elementor-nav-menu__align-end elementor-nav-menu--stretch elementor-nav-menu__text-align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"9445714\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;full_width&quot;:&quot;stretch&quot;,&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-9445714\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-99\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/inktcartridges\/\" class=\"elementor-item menu-link\">Inktcartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1517\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/epson-inktcartridges\/\" class=\"elementor-sub-item menu-link\">EPSON inktcartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8373\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t3100\/\" class=\"elementor-sub-item menu-link\">Supplies EPSON SC-T3100<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8385\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t3405\/\" class=\"elementor-sub-item menu-link\">Supplies EPSON SC-T3405<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8390\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t3700\/\" class=\"elementor-sub-item menu-link\">Supplies EPSON SC-T3700<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8412\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t5405\/\" class=\"elementor-sub-item menu-link\">Supplies EPSON SC-T5405<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8413\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t5700\/\" class=\"elementor-sub-item menu-link\">Supplies EPSON SC-T5700<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8415\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t7700\/\" class=\"elementor-sub-item menu-link\">Supplies EPSON SC-T7700<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8362\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-am-c4000\/\" class=\"elementor-sub-item menu-link\">Supplies EPSON AM-C4000<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8424\"><a href=\"https:\/\/cad.nl\/epson-inktcartridges\/\" class=\"elementor-sub-item menu-link\">Overige modellen<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1299\"><a href=\"https:\/\/cad.nl\/de\/hp-inktcartridges\/\" class=\"elementor-sub-item menu-link\">HP inktcartridges<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-614\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/tonercartridges\/\" class=\"elementor-item menu-link\">Tonercartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-685\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/kip-tonercartridges\/\" class=\"elementor-sub-item menu-link\">KIP tonercartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8437\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-71-serie\/\" class=\"elementor-sub-item menu-link\">Supplies KIP 71<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8438\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-75-serie\/\" class=\"elementor-sub-item menu-link\">Supplies KIP 75<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8439\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-770\/\" class=\"elementor-sub-item menu-link\">Supplies KIP 770<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8431\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-600-serie\/\" class=\"elementor-sub-item menu-link\">Supplies KIP 600<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8436\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-700c\/\" class=\"elementor-sub-item menu-link\">Supplies KIP 700C<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8440\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-800-serie\/\" class=\"elementor-sub-item menu-link\">Supplies KIP 800<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-684\"><a href=\"https:\/\/cad.nl\/de\/konica-minolta-tonercartridges\/\" class=\"elementor-sub-item menu-link\">Konica Minolta tonercartridges<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-100\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/papierrollen\/\" class=\"elementor-item menu-link\">Media<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-942\"><a href=\"https:\/\/cad.nl\/de\/papierrollen-2\/\" class=\"elementor-sub-item menu-link\">Papierrollen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-839\"><a href=\"https:\/\/cad.nl\/de\/kantoorpapier\/\" class=\"elementor-sub-item menu-link\">Kantoorpapier<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-product menu-item-7050\"><a href=\"https:\/\/cad.nl\/de\/produkt\/tab-rolls-111-mm-5-pieces\/\" class=\"elementor-sub-item menu-link\">EsteFold tab rolls 111 mm<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-98\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/kantoorprinters\/\" class=\"elementor-item menu-link\">Kantoorprinters<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-97\"><a href=\"https:\/\/cad.nl\/de\/printer-onderdelen\/\" class=\"elementor-sub-item menu-link\">Printer onderdelen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6696\"><a href=\"https:\/\/cad.nl\/de\/acco-brands-onderdelen\/\" class=\"elementor-item menu-link\">ACCO Brands<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6022\"><a href=\"https:\/\/cad.nl\/de\/my-account\/\" class=\"elementor-item menu-link\">Mijn account<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-6591\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages\/3#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor menu-link\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/cad.nl\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_DE.png\" width=\"18\" height=\"12\" alt=\"de_DE\" title=\"German\"><\/span><span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-6593\"><a href=\"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages\/3#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/cad.nl\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/nl_NL.png\" width=\"18\" height=\"12\" alt=\"nl_NL\" title=\"Dutch\"><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Men\u00fc Umschalter\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-9445714\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-99\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/inktcartridges\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Inktcartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1517\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/epson-inktcartridges\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">EPSON inktcartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8373\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t3100\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies EPSON SC-T3100<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8385\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t3405\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies EPSON SC-T3405<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8390\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t3700\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies EPSON SC-T3700<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8412\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t5405\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies EPSON SC-T5405<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8413\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t5700\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies EPSON SC-T5700<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8415\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-sc-t7700\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies EPSON SC-T7700<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8362\"><a href=\"https:\/\/cad.nl\/de\/supplies\/epson-inktcartridges\/supplies-epson-am-c4000\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies EPSON AM-C4000<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-8424\"><a href=\"https:\/\/cad.nl\/epson-inktcartridges\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Overige modellen<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1299\"><a href=\"https:\/\/cad.nl\/de\/hp-inktcartridges\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">HP inktcartridges<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-614\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/tonercartridges\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Tonercartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-685\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/kip-tonercartridges\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">KIP tonercartridges<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n\t<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8437\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-71-serie\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies KIP 71<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8438\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-75-serie\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies KIP 75<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8439\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-770\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies KIP 770<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8431\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-600-serie\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies KIP 600<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8436\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-700c\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies KIP 700C<\/a><\/li>\n\t\t<li class=\"menu-item menu-item-type-taxonomy menu-item-object-product_cat menu-item-8440\"><a href=\"https:\/\/cad.nl\/de\/supplies\/kip-tonercartridges\/supplies-kip-800-serie\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Supplies KIP 800<\/a><\/li>\n\t<\/ul>\n<\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-684\"><a href=\"https:\/\/cad.nl\/de\/konica-minolta-tonercartridges\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Konica Minolta tonercartridges<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-100\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/papierrollen\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Media<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-942\"><a href=\"https:\/\/cad.nl\/de\/papierrollen-2\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Papierrollen<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-839\"><a href=\"https:\/\/cad.nl\/de\/kantoorpapier\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Kantoorpapier<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-product menu-item-7050\"><a href=\"https:\/\/cad.nl\/de\/produkt\/tab-rolls-111-mm-5-pieces\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">EsteFold tab rolls 111 mm<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-98\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/kantoorprinters\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Kantoorprinters<span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-97\"><a href=\"https:\/\/cad.nl\/de\/printer-onderdelen\/\" class=\"elementor-sub-item menu-link\" tabindex=\"-1\">Printer onderdelen<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6696\"><a href=\"https:\/\/cad.nl\/de\/acco-brands-onderdelen\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">ACCO Brands<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-6022\"><a href=\"https:\/\/cad.nl\/de\/my-account\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Mijn account<\/a><\/li>\n<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher menu-item-has-children current-language-menu-item menu-item-6591\"><a aria-expanded=\"false\" href=\"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages\/3#TRPLINKPROCESSED\" class=\"elementor-item elementor-item-anchor menu-link\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/cad.nl\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/de_DE.png\" width=\"18\" height=\"12\" alt=\"de_DE\" title=\"German\"><\/span><span role=\"button\" class=\"dropdown-menu-toggle ast-header-navigation-arrow\" tabindex=\"0\" aria-expanded=\"false\" aria-label=\"Men\u00fc-Umschalter\" aria-haspopup=\"true\"><\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"trp-language-switcher-container menu-item menu-item-type-post_type menu-item-object-language_switcher current-language-menu-item menu-item-6593\"><a href=\"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages\/3#TRPLINKPROCESSED\" class=\"elementor-sub-item elementor-item-anchor menu-link\" tabindex=\"-1\"><span data-no-translation><img decoding=\"async\" class=\"trp-flag-image\" src=\"https:\/\/cad.nl\/wp-content\/plugins\/translatepress-multilingual\/assets\/images\/flags\/nl_NL.png\" width=\"18\" height=\"12\" alt=\"nl_NL\" title=\"Dutch\"><\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1030125\" data-id=\"1030125\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdc8acf elementor-menu-cart--empty-indicator-hide toggle-icon--cart-medium elementor-menu-cart--items-indicator-bubble elementor-menu-cart--show-subtotal-yes elementor-menu-cart--cart-type-side-cart elementor-menu-cart--show-remove-button-yes elementor-widget elementor-widget-woocommerce-menu-cart\" data-id=\"fdc8acf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cart_type&quot;:&quot;side-cart&quot;,&quot;open_cart&quot;:&quot;click&quot;,&quot;automatically_open_cart&quot;:&quot;no&quot;}\" data-widget_type=\"woocommerce-menu-cart.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-cart__wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-cart__toggle_wrapper\">\n\t\t\t\t\t<div class=\"elementor-menu-cart__container elementor-lightbox\" aria-hidden=\"true\">\n\t\t\t\t\t\t<div class=\"elementor-menu-cart__main\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-menu-cart__close-button\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"widget_shopping_cart_content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-menu-cart__toggle elementor-button-wrapper\">\n\t\t\t<a id=\"elementor-menu-cart__toggle_button\" href=\"#\" class=\"elementor-menu-cart__toggle_button elementor-button elementor-size-sm\" aria-expanded=\"false\">\n\t\t\t\t<span class=\"elementor-button-text\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>&nbsp;0,00<\/bdi><\/span><\/span>\n\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t<span class=\"elementor-button-icon-qty\" data-counter=\"0\">0<\/span>\n\t\t\t\t\t<i class=\"eicon-cart-medium\"><\/i>\t\t\t\t\t<span class=\"elementor-screen-only\">Warenkorb<\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div> <!-- close elementor-menu-cart__wrapper -->\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eeb1272 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"eeb1272\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fa459d\" data-id=\"7fa459d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b36bdc4 elementor-widget elementor-widget-spacer\" data-id=\"b36bdc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39fdd27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39fdd27\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b769567\" data-id=\"b769567\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04d83d1 elementor-widget elementor-widget-heading\" data-id=\"04d83d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Privacy Policy <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0416176 elementor-widget elementor-widget-heading\" data-id=\"0416176\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Voor CAD geldt dezelfde privacy policy als van Tomassen ICT Services BV. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17cc342 elementor-widget elementor-widget-text-editor\" data-id=\"17cc342\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Privacy statement van Tomassen ICT Services BV<\/b><br><b>Algemeen<\/b><br>Tomassen ICT Services waarborgt de privacy van de gebruikers van haar diensten en personeel. Tomassen ICT Services vindt Veiligheid en privacy van gebruikers belangrijk. Tomassen ICT Services handelt altijd in overeenstemming met de eisen die de Algemene Verordening Gegevensbescherming (AVG) aan haar stelt.<\/p>\n<p>In dit privacy statement worden het beleid en de uitgangspunten uiteengezet bij de verschillende manieren waarop Tomassen ICT Services persoonsgegevens verzamelt en de doeleinden waarvoor gegevens kunnen worden gebruikt.<br>Omdat Tomassen ICT Services haar diensten blijft ontwikkelen en verbeteren, kan het zijn dat dit privacy statement kan worden aangepast. Tomassen ICT Services publiceert dan ook steeds de meest actuele op haar website: www.tomassen.nl. Tomassen ICT Services is verantwoordelijk voor alle hieronder genoemde verwerkingen van persoonsgegevens.<\/p>\n<p><b>1. Grondslag voor het verzamelen en verwerken van persoonsgegevens<\/b><br>Tomassen ICT Services verwerkt persoonsgegevens over u doordat u gebruik maakt van onze diensten en\/of omdat u deze zelf aan ons verstrekt. Dat doet zij met de navolgende doeleinden:<br>1. om de overeengekomen producten en diensten te kunnen leveren, het afhandelen van bestellingen en om u daarover te informeren<br>2. het afhandelen van uw betaling of vergoedingen<br>3. om analyses uit te voeren en rapportages op te stellen ter verbetering van onze werkwijze<br>4. om te informeren over producten, evenementen, aanbiedingen en acties van Tomassen ICT Services, de nieuwsbrief<br>5. om uw gedrag op de website te analyseren ter verbetering van de website en ons aanbod van producten af te stemmen op uw voorkeuren<br>6. om informatie over u te verstrekken aan derden indien u daarvoor toestemming heeft gegeven<br>7. om informatie over u te verstrekken aan derden indien wij daartoe verplicht zijn op basis van wet- of regelgeving<br>8. om te controleren of u aan uw betalingsverplichtingen kunt voldoen alsmede ter controle van al die feiten en factoren die van belang zijn voor het verantwoord aangaan en\/of uitvoeren van de overeenkomst<br>9. om de website te beveiligen, aan te passen en te verbeteren<br>10. om uw identiteit te verifi\u00ebren en fraude tegen te gaan.<\/p>\n<p><b>2. De verschillende manieren waarop Tomassen ICT Services persoonsgegevens verzamelt en verwerkt, gekoppeld aan de doelstellingen<\/b><\/p>\n<p><b>2.1 (OP MAAT) BESTELLEN PRODUCTEN EN TE LEVEREN DIENSTEN<\/b><\/p>\n<p>Als u een bestelling plaatst voor een aantal bepaalde producten, vragen wij u bepaalde gegevens op te geven en zullen wij zelf bepaalde gegevens registreren. De grondslag hiervoor is de uitvoering van de overeenkomst, te weten: uw verzoek om bepaalde producten (op maat) te leveren.<br>Het gaat hierbij onder meer om de volgende (persoons)gegevens:<br>\u2022 E-mailadres<br>\u2022 Naam, adres en woonplaats<br>\u2022 Telefoonnummer<br>\u2022 Geslacht<br>\u2022 Kopie identiteitsbewijs van de bestuurder plus inschrijving KvK (het Burgerservicenummer (BSN) mag onleesbaar zijn. De kopie van het identiteitsbewijs wordt vernietigd zodra de controle is uitgevoerd.<br>\u2022 Bank- en betaalgegevens, creditcardgegevens<br>Wij bewaren deze gegevens zodat wij u goed kunnen adviseren en gebruiken de gegevens verder voor de volgende doeleinden: 1 t\/m 4, 6 t\/m 8 en 10.<\/p>\n<p><b>2.2 GEBRUIK VAN WEBSITE: WWW.TOMASSEN.NL OF WWW.CAD.NL<\/b><\/p>\n<p><b>Bezoek aan de website:<br><\/b>Als u de Tomassen ICT Services of CAD website bezoekt, verzamelen wij door middel van cookies bepaalde gegevens over u. Dit doen wij onder andere om de gebruiksvriendelijkheid van onze website te verhogen en om de website te beveiligen. Lees meer in onze Disclaimer die Tomassen ICT Services hanteert.<\/p>\n<p>Wij gebruiken de gegevens die wij verkrijgen in het kader van uw gebruik van de website voor de volgende doeleinden: 5 en 9.<\/p>\n<p><b>Bestellen via de website:<\/b><br>Als u online aankopen wilt doen via onze website, dan verwerken in dat geval de volgende gegevens:<br>\u2022 Naam, adres en woonplaats<br>\u2022 E-mailadres<br>\u2022 Telefoonnummer<br>\u2022 Bank- en betaalgegevens, creditcardgegevens<br>Wij gebruiken deze gegevens voor de volgende doeleinden: 1 t\/m 10.<\/p>\n<p><b>2.3 SOCIALE MEDIA<\/b><\/p>\n<p>Tomassen ICT Services is op verschillende sociale media aanwezig om u te kunnen blijven inspireren zoals Facebook, Twitter, Instagram, Pinterest, YouTube en Google plus.<br>Als u Tomassen ICT Services volgt via sociale media, of communiceert met of over Tomassen ICT Services via sociale media, verwerken wij de volgende gegevens zodat wij de inhoud van onze sociale media activiteiten voor onze klanten zoveel mogelijk kunnen optimaliseren:<br>\u2022 Profielinformatie van het betreffende sociale medium<br>\u2022 De bekeken en geplaatste content en berichten met betrekking tot Tomassen ICT Services<br>\u2022 In het platform opgeslagen metadata<br>Wij gebruiken deze gegevens voor de volgende doeleinden: 3, 4, 7.<\/p>\n<p><b>2.4 KLANTTEVREDENHEIDSONDERZOEKEN<\/b><\/p>\n<p>Indien u deelneemt aan een online klanttevredenheidsonderzoek van Tomassen ICT Services dan verwerken wij de volgende gegevens zodat de uitkomsten van het onderzoek gebruikt kunnen worden voor verbeteringen binnen Tomassen ICT Services in de breedste zin van het woord:<br>\u2022 Naam<br>\u2022 Adresgegevens<br>\u2022 E-mailadres<br>\u2022 Telefoonnummer<br>\u2022 Bestelling zelf<br>\u2022 Betaalgegevens<br>Wij gebruiken deze gegevens voor de volgende doeleinden: 3, 5 en 9.<\/p>\n<p><b>2.5 INFORMATIE OVER DIENSTEN VAN TOMASSEN ICT SERVICES<\/b><\/p>\n<p>Nieuwsbrief per e-mail<br>Indien u dat wenst ontvangt u periodiek de nieuwsbrief van Tomassen ICT Services per e-mail. U kunt bij een online bestelling aanvinken of u de nieuwbrief wilt ontvangen of hiervoor een formulier invullen of u hiervoor aanmelden via de website. De nieuwsbrief bevat informatie over producten en diensten en eventueel evenementen van Tomassen ICT Services.<br>Als u de nieuwsbrief van Tomassen ICT Services ontvangt, verzamelen wij de volgende gegevens:<br>\u2022 Naam<br>\u2022 Geslacht<br>\u2022 Adres, postcode en woonplaats<br>\u2022 E-mailadres<br>Wij gebruiken deze gegevens voor de volgende doeleinden: 3, 4, 7 t\/m 9.<br>Als u de nieuwsbrief niet langer wenst te ontvangen, kunt u zich afmelden aan het einde van de nieuwsbrief via een opt-out.<\/p>\n<p><b>3. VERSTREKKING GEGEVENS AAN DERDEN<\/b><\/p>\n<p>Tomassen ICT Services maakt gebruik van de diensten van derden om uw gegevens te verwerken maar zal dit altijd doen in overeenstemming met dit privacy statement. Deze derden treden hierbij op als (sub)bewerker voor Tomassen ICT Services. Tomassen ICT Services draagt de eindverantwoordelijkheid en zal er voor zorgen dat deze derden ook voldoende technische en organisatorische beveiligingsmaatregelen in acht nemen. Met bedrijven die klantengegevens verwerken in onze opdracht, sluit Tomassen ICT Services een verwerkersovereenkomst, om te zorgen voor eenzelfde niveau van beveiliging en vertrouwelijkheid van uw gegevens. Dit betekent onder andere dat deze derden de persoonsgegevens alleen voor Tomassen ICT Services mogen verwerken.<br>Voor het overige verstrekt Tomassen ICT Services alleen gegevens aan derden met uw voorafgaande toestemming of indien zij daartoe verplicht is op grond van wet- en regelgeving, zij daartoe genoodzaakt is als gevolg van een rechtszaak en\/of in het geval zij dat noodzakelijk acht ter bescherming van haar eigen belangen.<\/p>\n<p><b>4. BEWAARTERMIJNEN<\/b><\/p>\n<p>Tomassen ICT Services bewaart persoonsgegevens in overeenstemming met de wet niet langer dan noodzakelijk. De fysieke en digitale gegevens worden in elk geval uiterlijk zeven jaren bewaard in het geval er geen koop of dienstverlening meer heeft plaatsgevonden. De overige gegevens zoals de gegevens die op of via de website worden verstrekt (inclusief eventuele persoonsgegevens) bewaart Tomassen ICT Services uiterlijk vijf jaar vanaf het moment van vastlegging.<\/p>\n<p><b>5. INZAGE, CORRECTIE EN VERWIJDERING<\/b><\/p>\n<p>U heeft het recht uw persoonsgegevens in te zien, te corrigeren of te verwijderen. U kunt daartoe een verzoek tot inzage, correctie of verwijdering sturen naar: gert@Tomassen.nl<br>Om er zeker van te zijn dat het verzoek tot inzage door u is gedaan, vragen wij u een kopie of scan van uw identiteitsbewijs bij het verzoek mee te sturen. Hierbij vragen we u om in deze kopie of scan uw Burgerservicenummer (BSN) zwart te maken. Dit ter bescherming van uw privacy. Tomassen ICT Services zal zo snel mogelijk, maar uiterlijk binnen een maand, op uw verzoek inhoudelijk reageren.<\/p>\n<p><b>6. BEVEILIGING<\/b><\/p>\n<p>Tomassen ICT Services heeft passende technische en organisatorische maatregelen genomen om uw gegevens te beschermen tegen verlies of oneigenlijke verwerking. Wij hebben diverse beveiligingsmaatregelen getroffen om onbevoegde toegang te voorkomen en bewaakt permanent op diverse punten deze beveiligingsmaatregelen.<br>De gebruikersdata worden opgeslagen op locaties die zowel fysiek als technisch beveiligd zijn in Nederland. Tevens wordt er geregistreerd wie toegang heeft gehad tot de persoonsgegevens. Een beperkte groep medewerkers van Tomassen ICT Services heeft toegang tot de persoonsgegevens van de klanten op basis van zijn of haar functiebeschrijving. Die medewerkers die toegang hebben tot de klantendata worden vooraf getraind en ge\u00efnstrueerd hoe zij met de persoonsgegevens om dienen te gaan en er rust een geheimhoudingsplicht op hen.<\/p>\n<p><b>7. WIJZIGEN PRIVACY STATEMENT<\/b><\/p>\n<p>Tomassen ICT Services behoudt zich het recht voor deze Privacy statement of Privacy verklaring te wijzigen. De meest recente zal zij publiceren op haar website.<\/p>\n<p><b>8. CONTACT<\/b><\/p>\n<p>Indien u vragen heeft over uw privacy en over hoe wij met uw privacy omgaan, kunt u contact opnemen met ons via:<br>Tomassen ICT Services B.V.<br>Drs. W. van Royenstraat 2<br>3871 AN Hoevelaken<br>Telefoon: 033-25 800 80<br>E-mail: gert@tomassen.nl<\/p>\n<p>Communicatie per e-mail<br>Neem, indien u in de toekomst geen e-mails van ons wilt ontvangen, contact met ons op via het hierboven vermelde adres.<\/p>\n<p>Communicatie per brief<br>Als u uw adres heeft doorgegeven, zal Tomassen ICT Services u alleen de informatie daarop verstrekken die is aangevraagd.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c002262 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"c002262\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5ca9f6\" data-id=\"b5ca9f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b08f738 elementor-widget elementor-widget-spacer\" data-id=\"b08f738\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ef4294 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ef4294\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-26ef5a6\" data-id=\"26ef5a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eff0308 elementor-widget elementor-widget-image\" data-id=\"eff0308\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"829\" height=\"163\" src=\"https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2.png\" class=\"attachment-full size-full wp-image-6233\" alt=\"\" srcset=\"https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2.png 829w, https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2-300x59.png 300w, https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2-768x151.png 768w, https:\/\/cad.nl\/wp-content\/uploads\/2024\/05\/CAD-logo9514-2-2-600x118.png 600w\" sizes=\"(max-width: 829px) 100vw, 829px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb3c9e4 elementor-widget elementor-widget-text-editor\" data-id=\"eb3c9e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Supplies &amp; Media voor uw printerpark\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97bb1d2 elementor-widget elementor-widget-text-editor\" data-id=\"97bb1d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CAD is onderdeel van:<br \/><b>Tomassen ICT Services<\/b><\/p><p><b>KVK nummer<\/b>: 32090647<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6972be2\" data-id=\"6972be2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c1865c elementor-widget elementor-widget-heading\" data-id=\"1c1865c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Webshop<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c64007 elementor-widget elementor-widget-text-editor\" data-id=\"4c64007\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/cad.nl\/kantoorprinters\/\">Kantoorprinters<\/a><br \/><a href=\"https:\/\/cad.nl\/inktcartridges\/\">Inktcartridges<\/a><br \/><a href=\"https:\/\/cad.nl\/tonercartridges\/\">Tonercartridges<\/a><br \/><a href=\"https:\/\/cad.nl\/papierrollen-2\/\">Papierrollen<\/a><br \/><a href=\"https:\/\/cad.nl\/kantoorpapier\/\">Kantoorpapier<\/a><br \/><a href=\"https:\/\/cad.nl\/printer-onderdelen\/\">Onderdelen<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8629f3a\" data-id=\"8629f3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e8d01c elementor-widget elementor-widget-heading\" data-id=\"2e8d01c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Over CAD.nl<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a23e601 elementor-widget elementor-widget-text-editor\" data-id=\"a23e601\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/cad.nl\/contact\/\">Contact<\/a><br \/><a href=\"https:\/\/cad.nl\/over-cad\/\">Over CAD<\/a><br \/><a href=\"https:\/\/cad.nl\/contact\/\">Locatie<\/a><br \/><a href=\"https:\/\/cad.nl\/cad-afdrukken\/\">CAD afdrukken<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-72e511f\" data-id=\"72e511f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2abf6df elementor-widget elementor-widget-heading\" data-id=\"2abf6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Algemeen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-723e745 elementor-widget elementor-widget-text-editor\" data-id=\"723e745\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/cad.nl\/levertijden\/\">Levertijden<\/a><br \/><a href=\"https:\/\/cad.nl\/veelgestelde-vragen\/\">Veelgestelde vragen<\/a><br \/><a href=\"http:\/\/tomassen.nl\" target=\"_blank\" rel=\"noopener\">Tomassen ICT Services B.V.<\/a><br \/><a href=\"https:\/\/cad.nl\/algemene-voorwaarden\/\">Algemene voorwaarden<\/a><br \/><a href=\"https:\/\/cad.nl\/privacy-policy-2\/\">Privacy Policy<\/a><br \/><a href=\"https:\/\/cad.nl\/disclaimer\/\">Disclaimer<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0d4a55 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0d4a55\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-154e279\" data-id=\"154e279\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40a927c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"40a927c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf142fd elementor-widget elementor-widget-image\" data-id=\"bf142fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1702\" height=\"236\" src=\"https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad.png\" class=\"attachment-full size-full wp-image-2176\" alt=\"\" srcset=\"https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad.png 1702w, https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad-300x42.png 300w, https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad-1024x142.png 1024w, https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad-768x106.png 768w, https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad-1536x213.png 1536w, https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad-1320x183.png 1320w, https:\/\/cad.nl\/wp-content\/uploads\/2022\/10\/betaalmogelijkheden-cad-600x83.png 600w\" sizes=\"(max-width: 1702px) 100vw, 1702px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-27799dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"27799dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-928ced9\" data-id=\"928ced9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcce981 elementor-widget elementor-widget-text-editor\" data-id=\"bcce981\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Copyright \u00a9 | <span style=\"font-size: 14px; color: var( --e-global-color-accent );\">Powered by Tomassen ICT Services<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>+033 258 0080 info@tomassen.nl Tomassen ICT Services Privacy Policy Voor CAD geldt dezelfde privacy policy als van Tomassen ICT Services BV. Privacy statement van Tomassen ICT Services BVAlgemeenTomassen ICT Services waarborgt de privacy van de gebruikers van haar diensten en personeel. Tomassen ICT Services vindt Veiligheid en privacy van gebruikers belangrijk. Tomassen ICT Services handelt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"elementor_canvas","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":6,"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":7033,"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/pages\/3\/revisions\/7033"}],"wp:attachment":[{"href":"https:\/\/cad.nl\/de\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}